{"id":838,"date":"2025-03-21T10:33:50","date_gmt":"2025-03-21T10:33:50","guid":{"rendered":"https:\/\/dummy.xtemos.com\/woodmart2\/t-shirts\/?page_id=838"},"modified":"2026-08-25T22:28:58","modified_gmt":"2026-08-25T21:28:58","slug":"home","status":"publish","type":"page","link":"https:\/\/zoe.gatheomix.com\/fr\/","title":{"rendered":"Home"},"content":{"rendered":"<div class=\"wpb-content-wrapper\" id=\"wpb-content-root\"><div class=\"vc_row wpb_row vc_row-fluid hero-radius vc_custom_1783331687438 vc_row-has-fill vc_row-o-equal-height vc_row-o-content-bottom vc_row-flex wd-z-index wd-bg-center-center wd-rs-6a4b7b471d04f wd-section-stretch\"><div class=\"wpb_column vc_column_container vc_col-sm-3\/5 wd-z-index wd-enabled-flex wd-rs-6a4b7bd9969d2\"><div class=\"vc_column-inner vc_custom_1783331815500\"><div class=\"wpb_wrapper\">\n\t\t<div id=\"wd-6a4865a1b0fd8\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-6a4865a1b0fd8 wd-enabled-width wd-title-color-default wd-title-style-default text-left wd-off-anim wpb_animate_when_almost_visible wpb_flipInX flipInX wd-anim-name_flipInX vc_custom_1783129520259 wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title  wd-font-weight-600 wd-fontsize-l\" >Criamos Conceitos<\/h4>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t\t\t<div id=\"wd-6a4864dfbf05b\" class=\"wd-image wd-wpb wd-animation wd-transform wd-animation-slide-short-from-right wd-animation-normal wd_delay_1200 wd-rs-6a4864dfbf05b wd-enabled-width text-left vc_custom_1783129318935\">\n\t\t\t\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"82\" height=\"82\" src=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-top-min-1-opt.png\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t<div id=\"wd-6a4864cea94d2\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-animation wd-transform wd-animation-slide-from-top wd-animation-normal wd_delay_800 wd-rs-6a4864cea94d2 wd-enabled-width wd-title-color-default wd-title-style-default text-center vc_custom_1783129309181 wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title  wd-font-weight-600 wd-fontsize-l\" >Personalizamos<br \/>\no nosso Produto<\/h4>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t\t\t<div id=\"wd-6a4864cccd965\" class=\"wd-image wd-wpb wd-animation wd-transform wd-animation-slide-short-from-left wd-animation-normal wd_delay_1200 wd-rs-6a4864cccd965 wd-enabled-width text-left vc_custom_1783129326469\">\n\t\t\t\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"82\" height=\"82\" src=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-top-min-2-opt.png\" class=\"attachment-full size-full\" alt=\"\" \/>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t<div id=\"wd-6a4865376d5fe\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-animation wd-transform wd-animation-left-flip-y wd-animation-normal wd_delay_1500 wd-rs-6a4865376d5fe wd-enabled-width wd-title-color-default wd-title-style-default text-left vc_custom_1783129452735 wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title  wd-font-weight-600 wd-fontsize-l\" >Transformamos Ideias<\/h4>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t\n\t\t<div id=\"wd-6a4867714f082\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-6a4867714f082 wd-enabled-width wd-title-color-default wd-title-style-image text-left wd-off-anim wpb_animate_when_almost_visible wpb_bounceIn bounceIn wd-anim-name_bounceIn delay-2000 vc_custom_1783130100173 wd-title-empty wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title  wd-font-weight-800 wd-fontsize-l\" ><\/h4>\n\t\t\t\t\t\t\t\t\t<span class=\"img-wrapper\"><img decoding=\"async\"  src=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-bold-static-star.svg\" title=\"ps-bold-static-star\" loading=\"lazy\" width=\"60\" height=\"60\"><\/span>\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t\n\t\t<div id=\"wd-6a486a1538a07\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-6a486a1538a07 wd-enabled-width wd-title-color-default wd-title-style-default text-left wd-off-anim wpb_animate_when_almost_visible wpb_zoomInDown zoomInDown wd-anim-name_zoomInDown delay-2300 vc_custom_1783130692717 wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title  wd-font-weight-800 wd-fontsize-l\" >em Pe\u00e7as \u00danicas<\/h4>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t<div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_border_width_4 vc_sep_pos_align_center vc_separator_no_text vc_custom_1783130966786 delay-2600 wpb_animate_when_almost_visible wpb_left-to-right left-to-right\"   style=\"width: 100%;\"><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-top-color:#2A2A2A;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-top-color:#2A2A2A;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div>\t\t<div id=\"wd-6a486b47ac8d8\" class=\"wd-text-block wd-wpb reset-last-child wd-animation wd-transform wd-animation-top-flip-x wd-animation-normal wd_delay_3000 wd-rs-6a486b47ac8d8 hidden-md hidden-sm hidden-xs text-left wd-width-custom wd-fontsize-m\">\n\t\t\t<p>Criamos pe\u00e7as com a sua identidade, do conceito ao produto final. Escolha um modelo ou envie-nos a sua ideia.<\/p>\n\t\t<\/div>\n\t\t<div id=\"wd-6a486b6e11125\" class=\"wd-animation wd-transform wd-animation-zoom-in wd-animation-normal wd_delay_3300 wd-rs-6a486b6e11125  wd-button-wrapper text-left\"><a href=\"#\" title=\"\" class=\"btn btn-color-primary btn-style-default btn-shape-rectangle btn-size-extra-large\">Personalizar<\/a><\/div><\/div><\/div><\/div><div class=\"wpb_column hero-mancha-animada vc_column_container vc_col-sm-2\/5 wd-enabled-flex wd-rs-6a4870e5d74a4\"><div class=\"vc_column-inner vc_custom_1783132393886\"><div class=\"wpb_wrapper\">\t\t<div id=\"wd-6a8d8ca4d0865\" class=\"wd-image wd-wpb wd-rs-6a8d8ca4d0865 text-center vc_custom_1787661678808\">\n\t\t\t\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"667\" height=\"1000\" src=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2026\/08\/pirata.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2026\/08\/pirata.webp 667w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2026\/08\/pirata-200x300.webp 200w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2026\/08\/pirata-534x800.webp 534w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2026\/08\/pirata-8x12.webp 8w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2026\/08\/pirata-430x645.webp 430w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2026\/08\/pirata-180x270.webp 180w\" sizes=\"auto, (max-width: 667px) 100vw, 667px\" \/>\n\t\t\t\t\t<\/div>\n\t\t<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1783328876152 vc_row-has-fill wd-z-index wd-rs-6a4b7052d0789 wd-section-stretch\"><div class=\"wpb_column vc_column_container vc_col-sm-12 wd-rs-67d8112d775f9\"><div class=\"vc_column-inner vc_custom_1742213424638\"><div class=\"wpb_wrapper\">\n\t\t<div id=\"wd-6a8b0f92acce9\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-6a8b0f92acce9 wd-title-color-default wd-title-style-default text-left vc_custom_1787498406953 wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-l\" >O Produto...<\/h4>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<div class=\"products wd-carousel-container wd-cats-element wd-rs-683486675413b wd-wpb vc_custom_1748272748520 wd-cats\">\n\t\t\t\t\t<div class=\"wd-carousel-inner\">\n\t\t\t\t\t\t<div class=\"wd-carousel wd-grid\" data-scroll_per_page=\"yes\" style=\"--wd-col-lg:4;--wd-col-md:3;--wd-col-sm:2;--wd-gap-lg:20px;--wd-gap-sm:10px;\">\n\t\t\t\t\t\t\t<div class=\"wd-carousel-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\n<div class=\"category-grid-item wd-cat cat-design-center without-product-count wd-with-subcat product-category product first\" data-loop=\"1\">\n\t\n\t<div class=\"wd-cat-inner wrapp-category\">\n\t\t<div class=\"wd-cat-thumb category-image-wrapp\">\n\t\t\t<a class=\"wd-cat-image category-image\" href=\"https:\/\/zoe.gatheomix.com\/fr\/product-category\/autocolantes\/\" aria-label=\"Autocolantes\">\n\t\t\t\t\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"244\" height=\"400\" src=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-category-4-opt.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-category-4-opt.jpg 244w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-category-4-opt-180x295.jpg 180w\" sizes=\"auto, (max-width: 244px) 100vw, 244px\" \/>\t\t\t<\/a>\n\t\t<\/div>\n\t\t<div class=\"wd-cat-content hover-mask\">\n\t\t\t<h3 class=\"wd-entities-title\">\n\t\t\t\tAutocolantes\t\t\t<\/h3>\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t<a class=\"wd-fill category-link\" href=\"https:\/\/zoe.gatheomix.com\/fr\/product-category\/autocolantes\/\" aria-label=\"Product category autocolantes\"><\/a>\n\t\t\t<\/div>\n\n\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\n<div class=\"category-grid-item wd-cat cat-design-center without-product-count wd-with-subcat product-category product\" data-loop=\"2\">\n\t\n\t<div class=\"wd-cat-inner wrapp-category\">\n\t\t<div class=\"wd-cat-thumb category-image-wrapp\">\n\t\t\t<a class=\"wd-cat-image category-image\" href=\"https:\/\/zoe.gatheomix.com\/fr\/product-category\/quadros-de-rotinas\/\" aria-label=\"Quadros de Rotinas\">\n\t\t\t\t\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"244\" height=\"400\" src=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-category-5-opt.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-category-5-opt.jpg 244w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-category-5-opt-180x295.jpg 180w\" sizes=\"auto, (max-width: 244px) 100vw, 244px\" \/>\t\t\t<\/a>\n\t\t<\/div>\n\t\t<div class=\"wd-cat-content hover-mask\">\n\t\t\t<h3 class=\"wd-entities-title\">\n\t\t\t\tQuadros de Rotinas\t\t\t<\/h3>\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t<a class=\"wd-fill category-link\" href=\"https:\/\/zoe.gatheomix.com\/fr\/product-category\/quadros-de-rotinas\/\" aria-label=\"Product category quadros-de-rotinas\"><\/a>\n\t\t\t<\/div>\n\n\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\n<div class=\"category-grid-item wd-cat cat-design-center without-product-count wd-with-subcat product-category product\" data-loop=\"3\">\n\t\n\t<div class=\"wd-cat-inner wrapp-category\">\n\t\t<div class=\"wd-cat-thumb category-image-wrapp\">\n\t\t\t<a class=\"wd-cat-image category-image\" href=\"https:\/\/zoe.gatheomix.com\/fr\/product-category\/vestuario\/\" aria-label=\"Vestu\u00e1rio\">\n\t\t\t\t\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"244\" height=\"400\" src=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2026\/08\/category-clothes.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2026\/08\/category-clothes.webp 244w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2026\/08\/category-clothes-183x300.webp 183w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2026\/08\/category-clothes-7x12.webp 7w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2026\/08\/category-clothes-180x295.webp 180w\" sizes=\"auto, (max-width: 244px) 100vw, 244px\" \/>\t\t\t<\/a>\n\t\t<\/div>\n\t\t<div class=\"wd-cat-content hover-mask\">\n\t\t\t<h3 class=\"wd-entities-title\">\n\t\t\t\tVestu\u00e1rio\t\t\t<\/h3>\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t<a class=\"wd-fill category-link\" href=\"https:\/\/zoe.gatheomix.com\/fr\/product-category\/vestuario\/\" aria-label=\"Product category vestuario\"><\/a>\n\t\t\t<\/div>\n\n\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\n<div class=\"category-grid-item wd-cat cat-design-center without-product-count wd-with-subcat product-category product last\" data-loop=\"4\">\n\t\n\t<div class=\"wd-cat-inner wrapp-category\">\n\t\t<div class=\"wd-cat-thumb category-image-wrapp\">\n\t\t\t<a class=\"wd-cat-image category-image\" href=\"https:\/\/zoe.gatheomix.com\/fr\/product-category\/wall-art\/\" aria-label=\"Wall Art\">\n\t\t\t\t\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"244\" height=\"400\" src=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-category-3-opt.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-category-3-opt.jpg 244w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-category-3-opt-180x295.jpg 180w\" sizes=\"auto, (max-width: 244px) 100vw, 244px\" \/>\t\t\t<\/a>\n\t\t<\/div>\n\t\t<div class=\"wd-cat-content hover-mask\">\n\t\t\t<h3 class=\"wd-entities-title\">\n\t\t\t\tWall Art\t\t\t<\/h3>\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t<a class=\"wd-fill category-link\" href=\"https:\/\/zoe.gatheomix.com\/fr\/product-category\/wall-art\/\" aria-label=\"Product category wall-art\"><\/a>\n\t\t\t<\/div>\n\n\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"wd-nav-arrows wd-pos-sep wd-hover-1 wd-icon-1\">\n\t\t\t<div class=\"wd-btn-arrow wd-prev wd-disabled\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"wd-btn-arrow wd-next\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_border_width_4 vc_sep_pos_align_center vc_separator_no_text vc_custom_1742214208133\"   style=\"width: 100%;\"><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-top-color:#2A2A2A;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-top-color:#2A2A2A;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1783118350138 vc_row-o-equal-height vc_row-flex wd-rs-6a483a0abc28f\"><div class=\"wpb_column vc_column_container vc_col-sm-6 vc_col-lg-4 woodmart-sticky-column wd_sticky_offset_150 wd-rs-6a4839f09ad9b\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\t\t\t<div class=\"info-box-wrapper\">\n\t\t\t\t\t\t\t\t<div id=\"wd-6a483b135b701\" class=\"wd-rs-6a483b135b701 wd-info-box wd-wpb text-left box-icon-align-right box-style- color-scheme- wd-bg-none wd-items-bottom vc_custom_1783118644974\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"box-icon-wrapper  box-with-icon box-icon-simple\">\n\t\t\t\t\t\t\t<div class=\"info-box-icon\">\n\t\t\t\t\t\t\t\t<div class=\"info-svg-wrapper\" style=\"width: 64px;height: 64px;\"><img decoding=\"async\"  src=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-bold-arrow-left.svg\" title=\"ps-bold-arrow-left\" loading=\"lazy\" width=\"64\" height=\"64\"><\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"info-box-content\">\n\t\t\t\t\t\t<h4 class=\"info-box-title title box-title-style-default wd-fontsize-m\">Privil\u00e9gios da nossa marca<\/h4>\t\t\t\t\t\t<div class=\"info-box-inner reset-last-child\"><\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div id=\"wd-6a483a29e9c5e\" class=\"wd-text-block wd-wpb reset-last-child wd-rs-6a483a29e9c5e text-left wd-fontsize-custom vc_custom_1783118386444\">\n\t\t\t<p>Imprimiremos qualquer uma das suas imagens, fotos, log\u00f3tipo da empresa, identidade corporativa ou simplesmente uma inscri\u00e7\u00e3o \u00e0 sua escolha. Escolha um modelo do nosso cat\u00e1logo ou forne\u00e7a o seu pr\u00f3prio material para concretizar as suas ideias.<\/p>\n\t\t<\/div>\n\t\t<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6 vc_col-lg-4 wd-rs-67d81ae0022f5\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\t\t<div id=\"wd-67d81877bc1e9\" class=\"wd-image wd-wpb wd-rs-67d81877bc1e9 text-center\">\n\t\t\t\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"402\" height=\"522\" src=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-center-girl-opt.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-center-girl-opt.png 402w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-center-girl-opt-180x234.png 180w\" sizes=\"auto, (max-width: 402px) 100vw, 402px\" \/>\n\t\t\t\t\t<\/div>\n\t\t<div id=\"wd-6a483a743e248\" class=\"wd-rs-6a483a743e248  wd-button-wrapper text-center\"><a href=\"#\" title=\"\" class=\"btn btn-color-primary btn-style-default btn-shape-rectangle btn-size-extra-large btn-full-width\">Ver Produtos<\/a><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-lg-4 wd-enabled-flex woodmart-sticky-column wd_sticky_offset_150 wd-rs-6a483a152afbd\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\t\t\t<div class=\"info-box-wrapper\">\n\t\t\t\t\t\t\t\t<div id=\"wd-6a4852472d37b\" class=\"wd-rs-6a4852472d37b wd-info-box wd-wpb text-left box-icon-align-left box-style- color-scheme- wd-bg-none wd-items-middle vc_custom_1783124560825\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"box-icon-wrapper  box-with-icon box-icon-simple\">\n\t\t\t\t\t\t\t<div class=\"info-box-icon\">\n\t\t\t\t\t\t\t\t<div class=\"info-svg-wrapper\" style=\"width: 64px;height: 64px;\"><img decoding=\"async\"  src=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-color-star-4.svg\" title=\"ps-color-star-4\" loading=\"lazy\" width=\"64\" height=\"64\"><\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"info-box-content\">\n\t\t\t\t\t\t<h4 class=\"info-box-title title box-title-style-default wd-fontsize-m\">Encomendas R\u00e1pidas<\/h4>\t\t\t\t\t\t<div class=\"info-box-inner reset-last-child\"><p>Enviamos a encomenda em 48 horas<br \/>\n(<a href=\"#\">ver condi\u00e7\u00f5es<\/a>)<\/p>\n<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"info-box-wrapper\">\n\t\t\t\t\t\t\t\t<div id=\"wd-6a8b0fb113af1\" class=\"wd-rs-6a8b0fb113af1 wd-info-box wd-wpb text-left box-icon-align-left box-style- color-scheme- wd-bg-none wd-items-middle vc_custom_1787498538458\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"box-icon-wrapper  box-with-icon box-icon-simple\">\n\t\t\t\t\t\t\t<div class=\"info-box-icon\">\n\t\t\t\t\t\t\t\t<div class=\"info-svg-wrapper\" style=\"width: 64px;height: 64px;\"><img decoding=\"async\"  src=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-color-star-32.svg\" title=\"ps-color-star-32\" loading=\"lazy\" width=\"64\" height=\"64\"><\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"info-box-content\">\n\t\t\t\t\t\t<h4 class=\"info-box-title title box-title-style-default wd-fontsize-m\">Materiais de Qualidade<\/h4>\t\t\t\t\t\t<div class=\"info-box-inner reset-last-child\"><p>Utilizamos t\u00eaxteis e outros materiais cuidadosamente selecionados<\/p>\n<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"info-box-wrapper\">\n\t\t\t\t\t\t\t\t<div id=\"wd-6a8b1032359c1\" class=\"wd-rs-6a8b1032359c1 wd-info-box wd-wpb text-left box-icon-align-left box-style- color-scheme- wd-bg-none wd-items-middle vc_custom_1787498769885\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"box-icon-wrapper  box-with-icon box-icon-simple\">\n\t\t\t\t\t\t\t<div class=\"info-box-icon\">\n\t\t\t\t\t\t\t\t<div class=\"info-svg-wrapper\" style=\"width: 64px;height: 64px;\"><img decoding=\"async\"  src=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-color-star-8.svg\" title=\"ps-color-star-8\" loading=\"lazy\" width=\"64\" height=\"64\"><\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"info-box-content\">\n\t\t\t\t\t\t<h4 class=\"info-box-title title box-title-style-default wd-fontsize-m\">Feito \u00e0 Sua Medida<\/h4>\t\t\t\t\t\t<div class=\"info-box-inner reset-last-child\"><p>Personalizamos cada pe\u00e7a de acordo com a sua ideia.<\/p>\n<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12 wd-rs-67d81c2e77756\"><div class=\"vc_column-inner vc_custom_1742216242578\"><div class=\"wpb_wrapper\"><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_border_width_4 vc_sep_pos_align_center vc_separator_no_text vc_custom_1742214214147\"   style=\"width: 100%;\"><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-top-color:#2A2A2A;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-top-color:#2A2A2A;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div>\t\t\t<div class=\"wd-products-element wd-rs-6a8b111d18774 vc_custom_1787498800101 wd-wpb with-title\">\n\t\t\t<h4 class=\"wd-el-title title element-title\">Produtos Populares<\/h4>\n\t\t\n\t\t\t\t\t<div class=\"products wd-products  grid-columns-4 elements-grid wd-grid-g wd-loop-builder-off wd-stretch-cont-lg\" data-paged=\"1\" data-atts=\"{&quot;css&quot;:&quot;.vc_custom_1787498800101{margin-top: 80px !important;margin-bottom: 40px !important;}&quot;,&quot;element_title&quot;:&quot;Produtos Populares&quot;,&quot;items_per_page&quot;:&quot;8&quot;,&quot;columns_tablet&quot;:&quot;3&quot;,&quot;sale_countdown&quot;:&quot;0&quot;,&quot;stock_progress_bar&quot;:&quot;0&quot;,&quot;highlighted_products&quot;:&quot;0&quot;,&quot;products_bordered_grid&quot;:&quot;0&quot;,&quot;products_with_background&quot;:&quot;0&quot;,&quot;products_shadow&quot;:&quot;0&quot;,&quot;woodmart_css_id&quot;:&quot;6a8b111d18774&quot;,&quot;force_not_ajax&quot;:&quot;no&quot;}\" data-source=\"shortcode\" data-columns=\"4\" style=\"--wd-col-lg:4;--wd-col-md:3;--wd-col-sm:2;--wd-gap-lg:20px;--wd-gap-sm:10px;\">\n\t\t\t<div class=\"wd-product wd-col wd-hover-standard product-grid-item product type-product post-324 status-publish instock product_cat-vestuario has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"1\" data-id=\"324\">\n\t\n<div class=\"wd-product-wrapper product-wrapper\">\n\t<div class=\"wd-product-thumb product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/zoe.gatheomix.com\/fr\/loja\/vestuario\/active-t-shirt\/\" class=\"wd-product-img-link product-image-link\" tabindex=\"-1\" aria-label=\"Active-T-Shirt\">\n\t\t\t\t\t<div class=\"wd-product-grid-slider wd-fill\">\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slide\" data-image-url=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-a-ts-0-430x491.jpg\" data-image-srcset=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-a-ts-0-430x491.jpg 430w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-a-ts-0-180x206.jpg 180w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-a-ts-0.jpg 700w\" data-image-id=\"0\"><\/div>\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slide\" data-image-url=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-swtst-6-430x491.jpg\" data-image-srcset=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-swtst-6-430x491.jpg 430w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-swtst-6-180x206.jpg 180w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-swtst-6.jpg 700w\" data-image-id=\"1\"><\/div>\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slide\" data-image-url=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-jt-tot-bg-0-430x491.jpg\" data-image-srcset=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-jt-tot-bg-0-430x491.jpg 430w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-jt-tot-bg-0-180x206.jpg 180w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-jt-tot-bg-0.jpg 700w\" data-image-id=\"2\"><\/div>\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slide\" data-image-url=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-tap-pos-0-430x491.jpg\" data-image-srcset=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-tap-pos-0-430x491.jpg 430w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-tap-pos-0-180x206.jpg 180w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-tap-pos-0.jpg 700w\" data-image-id=\"3\"><\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slider-pagin\">\n\t\t\t\t\t\t\t<div data-image-id=\"0\" class=\"wd-product-grid-slider-dot\"><\/div>\n\t\t\t\t\t\t\t<div data-image-id=\"1\" class=\"wd-product-grid-slider-dot\"><\/div>\n\t\t\t\t\t\t\t<div data-image-id=\"2\" class=\"wd-product-grid-slider-dot\"><\/div>\n\t\t\t\t\t\t\t<div data-image-id=\"3\" class=\"wd-product-grid-slider-dot\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"430\" height=\"491\" src=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-a-ts-0-430x491.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-a-ts-0-430x491.jpg 430w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-a-ts-0-180x206.jpg 180w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-a-ts-0.jpg 700w\" sizes=\"auto, (max-width: 430px) 100vw, 430px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/zoe.gatheomix.com\/fr\/compare\/\" class=\"\" data-id=\"324\" rel=\"nofollow\">\n\t\t\t\t<span class=\"wd-action-icon\">\n\t\t\t\t\t<span class=\"wd-check-icon\"><\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class=\"wd-action-text\">Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"wd-quick-view-btn wd-quick-view-icon wd-action-btn wd-style-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/zoe.gatheomix.com\/fr\/loja\/vestuario\/active-t-shirt\/\"\n\t\t\t\tclass=\"open-quick-view\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"324\"\n\t\t\t\t>\n\t\t\t\t\t<span class=\"wd-action-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">\n\t\t\t\t\t\tQuick view\t\t\t\t\t<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/zoe.gatheomix.com\/fr\/wishlist\/\" data-key=\"39ec3b8ab4\" data-product-id=\"324\" rel=\"nofollow\">\n\t\t\t\t\t<span class=\"wd-action-icon\">\n\t\t\t\t\t\t<span class=\"wd-check-icon\"><\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t<\/div>\n\n\t\t<div class=\"product-element-bottom\">\n\t\n\t\n\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/zoe.gatheomix.com\/fr\/loja\/vestuario\/active-t-shirt\/\">Active-T-Shirt<\/a><\/h3>\n\t\t\t\n\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>18,00<span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span><\/bdi><\/span><\/span>\n\n\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\n\t\t<a href=\"\/fr\/wp-json\/wp\/v2\/pages\/838?add-to-cart=324\"  data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"324\" data-product_sku=\"TS-1227\" aria-label=\"Ajouter au panier\u00a0: \u201cActive-T-Shirt\u201d\" rel=\"nofollow\" data-success_message=\"\u00ab\u00a0Active-T-Shirt\u00a0\u00bb a \u00e9t\u00e9 ajout\u00e9 \u00e0 votre panier\" role=\"button\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\"><span class=\"wd-action-icon\"><span class=\"wd-check-icon\"><\/span><\/span><span class=\"wd-action-text\" data-no-translation=\"\" data-trp-gettext=\"\">Ajouter au panier<\/span><\/a>\t<\/div>\n\n\t\n\t\n\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<div class=\"wd-product wd-col wd-hover-standard product-grid-item product type-product post-512 status-publish instock product_cat-wall-art has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"2\" data-id=\"512\">\n\t\n<div class=\"wd-product-wrapper product-wrapper\">\n\t<div class=\"wd-product-thumb product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/zoe.gatheomix.com\/fr\/loja\/wall-art\/art-board-print\/\" class=\"wd-product-img-link product-image-link\" tabindex=\"-1\" aria-label=\"Art Board Print\">\n\t\t\t\t\t<div class=\"wd-product-grid-slider wd-fill\">\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slide\" data-image-url=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-art-brd-0-430x491.jpg\" data-image-srcset=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-art-brd-0-430x491.jpg 430w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-art-brd-0-180x206.jpg 180w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-art-brd-0.jpg 700w\" data-image-id=\"0\"><\/div>\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slide\" data-image-url=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-bsb-cap-0-430x491.jpg\" data-image-srcset=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-bsb-cap-0-430x491.jpg 430w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-bsb-cap-0-180x206.jpg 180w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-bsb-cap-0.jpg 700w\" data-image-id=\"1\"><\/div>\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slide\" data-image-url=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-swtst-7-430x491.jpg\" data-image-srcset=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-swtst-7-430x491.jpg 430w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-swtst-7-180x206.jpg 180w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-swtst-7.jpg 700w\" data-image-id=\"2\"><\/div>\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slide\" data-image-url=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-mug-2-430x491.jpg\" data-image-srcset=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-mug-2-430x491.jpg 430w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-mug-2-180x206.jpg 180w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-mug-2.jpg 700w\" data-image-id=\"3\"><\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slider-pagin\">\n\t\t\t\t\t\t\t<div data-image-id=\"0\" class=\"wd-product-grid-slider-dot\"><\/div>\n\t\t\t\t\t\t\t<div data-image-id=\"1\" class=\"wd-product-grid-slider-dot\"><\/div>\n\t\t\t\t\t\t\t<div data-image-id=\"2\" class=\"wd-product-grid-slider-dot\"><\/div>\n\t\t\t\t\t\t\t<div data-image-id=\"3\" class=\"wd-product-grid-slider-dot\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"430\" height=\"491\" src=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-art-brd-0-430x491.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-art-brd-0-430x491.jpg 430w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-art-brd-0-180x206.jpg 180w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-art-brd-0.jpg 700w\" sizes=\"auto, (max-width: 430px) 100vw, 430px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/zoe.gatheomix.com\/fr\/compare\/\" class=\"\" data-id=\"512\" rel=\"nofollow\">\n\t\t\t\t<span class=\"wd-action-icon\">\n\t\t\t\t\t<span class=\"wd-check-icon\"><\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class=\"wd-action-text\">Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"wd-quick-view-btn wd-quick-view-icon wd-action-btn wd-style-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/zoe.gatheomix.com\/fr\/loja\/wall-art\/art-board-print\/\"\n\t\t\t\tclass=\"open-quick-view\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"512\"\n\t\t\t\t>\n\t\t\t\t\t<span class=\"wd-action-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">\n\t\t\t\t\t\tQuick view\t\t\t\t\t<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/zoe.gatheomix.com\/fr\/wishlist\/\" data-key=\"39ec3b8ab4\" data-product-id=\"512\" rel=\"nofollow\">\n\t\t\t\t\t<span class=\"wd-action-icon\">\n\t\t\t\t\t\t<span class=\"wd-check-icon\"><\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t<\/div>\n\n\t\t<div class=\"product-element-bottom\">\n\t\n\t\n\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/zoe.gatheomix.com\/fr\/loja\/wall-art\/art-board-print\/\">Art Board Print<\/a><\/h3>\n\t\t\t\n\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>9,00<span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span><\/bdi><\/span><\/span>\n\n\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\n\t\t<a href=\"\/fr\/wp-json\/wp\/v2\/pages\/838?add-to-cart=512\"  data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"512\" data-product_sku=\"TS-1240\" aria-label=\"Ajouter au panier\u00a0: \u201cArt Board Print\u201d\" rel=\"nofollow\" data-success_message=\"\u00ab\u00a0Art Board Print\u00a0\u00bb a \u00e9t\u00e9 ajout\u00e9 \u00e0 votre panier\" role=\"button\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\"><span class=\"wd-action-icon\"><span class=\"wd-check-icon\"><\/span><\/span><span class=\"wd-action-text\" data-no-translation=\"\" data-trp-gettext=\"\">Ajouter au panier<\/span><\/a>\t<\/div>\n\n\t\n\t\n\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<div class=\"wd-product wd-col wd-hover-standard product-grid-item product type-product post-464 status-publish last instock product_cat-wall-art has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"3\" data-id=\"464\">\n\t\n<div class=\"wd-product-wrapper product-wrapper\">\n\t<div class=\"wd-product-thumb product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/zoe.gatheomix.com\/fr\/loja\/wall-art\/art-print\/\" class=\"wd-product-img-link product-image-link\" tabindex=\"-1\" aria-label=\"Art Print\">\n\t\t\t\t\t<div class=\"wd-product-grid-slider wd-fill\">\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slide\" data-image-url=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-art-pr-0-430x491.jpg\" data-image-srcset=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-art-pr-0-430x491.jpg 430w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-art-pr-0-180x206.jpg 180w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-art-pr-0.jpg 700w\" data-image-id=\"0\"><\/div>\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slide\" data-image-url=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-die-cut-st-0-430x491.jpg\" data-image-srcset=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-die-cut-st-0-430x491.jpg 430w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-die-cut-st-0-180x206.jpg 180w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-die-cut-st-0.jpg 700w\" data-image-id=\"1\"><\/div>\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slide\" data-image-url=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-v-ts-0-430x491.jpg\" data-image-srcset=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-v-ts-0-430x491.jpg 430w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-v-ts-0-180x206.jpg 180w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-v-ts-0.jpg 700w\" data-image-id=\"2\"><\/div>\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slide\" data-image-url=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-st-th-0-430x491.jpg\" data-image-srcset=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-st-th-0-430x491.jpg 430w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-st-th-0-180x206.jpg 180w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-st-th-0.jpg 700w\" data-image-id=\"3\"><\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slider-pagin\">\n\t\t\t\t\t\t\t<div data-image-id=\"0\" class=\"wd-product-grid-slider-dot\"><\/div>\n\t\t\t\t\t\t\t<div data-image-id=\"1\" class=\"wd-product-grid-slider-dot\"><\/div>\n\t\t\t\t\t\t\t<div data-image-id=\"2\" class=\"wd-product-grid-slider-dot\"><\/div>\n\t\t\t\t\t\t\t<div data-image-id=\"3\" class=\"wd-product-grid-slider-dot\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"430\" height=\"491\" src=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-art-pr-0-430x491.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-art-pr-0-430x491.jpg 430w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-art-pr-0-180x206.jpg 180w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-art-pr-0.jpg 700w\" sizes=\"auto, (max-width: 430px) 100vw, 430px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/zoe.gatheomix.com\/fr\/compare\/\" class=\"\" data-id=\"464\" rel=\"nofollow\">\n\t\t\t\t<span class=\"wd-action-icon\">\n\t\t\t\t\t<span class=\"wd-check-icon\"><\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class=\"wd-action-text\">Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"wd-quick-view-btn wd-quick-view-icon wd-action-btn wd-style-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/zoe.gatheomix.com\/fr\/loja\/wall-art\/art-print\/\"\n\t\t\t\tclass=\"open-quick-view\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"464\"\n\t\t\t\t>\n\t\t\t\t\t<span class=\"wd-action-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">\n\t\t\t\t\t\tQuick view\t\t\t\t\t<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/zoe.gatheomix.com\/fr\/wishlist\/\" data-key=\"39ec3b8ab4\" data-product-id=\"464\" rel=\"nofollow\">\n\t\t\t\t\t<span class=\"wd-action-icon\">\n\t\t\t\t\t\t<span class=\"wd-check-icon\"><\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t<\/div>\n\n\t\t<div class=\"product-element-bottom\">\n\t\n\t\n\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/zoe.gatheomix.com\/fr\/loja\/wall-art\/art-print\/\">Art Print<\/a><\/h3>\n\t\t\t\n\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>12,00<span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span><\/bdi><\/span><\/span>\n\n\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\n\t\t<a href=\"\/fr\/wp-json\/wp\/v2\/pages\/838?add-to-cart=464\"  data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"464\" data-product_sku=\"TS-1236\" aria-label=\"Ajouter au panier\u00a0: \u201cArt Print\u201d\" rel=\"nofollow\" data-success_message=\"\u00ab\u00a0Art Print\u00a0\u00bb a \u00e9t\u00e9 ajout\u00e9 \u00e0 votre panier\" role=\"button\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\"><span class=\"wd-action-icon\"><span class=\"wd-check-icon\"><\/span><\/span><span class=\"wd-action-text\" data-no-translation=\"\" data-trp-gettext=\"\">Ajouter au panier<\/span><\/a>\t<\/div>\n\n\t\n\t\n\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<div class=\"wd-product wd-col wd-hover-standard product-grid-item product type-product post-990 status-publish first outofstock product_cat-autocolantes shipping-taxable product-type-variable\" data-loop=\"4\" data-id=\"990\">\n\t\n<div class=\"wd-product-wrapper product-wrapper\">\n\t<div class=\"wd-product-thumb product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/zoe.gatheomix.com\/fr\/loja\/autocolantes\/baby-on-board\/\" class=\"wd-product-img-link product-image-link\" tabindex=\"-1\" aria-label=\"BABY ON BOARD\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"430\" height=\"430\" src=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/woocommerce-placeholder-430x430.webp\" class=\"woocommerce-placeholder wp-post-image\" alt=\"Texte indicatif\" srcset=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/woocommerce-placeholder-430x430.webp 430w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/woocommerce-placeholder-180x180.webp 180w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/woocommerce-placeholder-700x700.webp 700w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/woocommerce-placeholder-300x300.webp 300w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/woocommerce-placeholder-1024x1024.webp 1024w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/woocommerce-placeholder-150x150.webp 150w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/woocommerce-placeholder-768x768.webp 768w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/woocommerce-placeholder.webp 1200w\" sizes=\"auto, (max-width: 430px) 100vw, 430px\" data-no-translation-alt=\"\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"product-labels labels-rectangular\">\n\t\t\t\t<span class=\"out-of-stock product-label wd-shape-rect-sm\">Sold out<\/span>\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/zoe.gatheomix.com\/fr\/compare\/\" class=\"\" data-id=\"990\" rel=\"nofollow\">\n\t\t\t\t<span class=\"wd-action-icon\">\n\t\t\t\t\t<span class=\"wd-check-icon\"><\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class=\"wd-action-text\">Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"wd-quick-view-btn wd-quick-view-icon wd-action-btn wd-style-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/zoe.gatheomix.com\/fr\/loja\/autocolantes\/baby-on-board\/\"\n\t\t\t\tclass=\"open-quick-view\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"990\"\n\t\t\t\t>\n\t\t\t\t\t<span class=\"wd-action-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">\n\t\t\t\t\t\tQuick view\t\t\t\t\t<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/zoe.gatheomix.com\/fr\/wishlist\/\" data-key=\"39ec3b8ab4\" data-product-id=\"990\" rel=\"nofollow\">\n\t\t\t\t\t<span class=\"wd-action-icon\">\n\t\t\t\t\t\t<span class=\"wd-check-icon\"><\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t<\/div>\n\n\t\t<div class=\"product-element-bottom\">\n\t\n\t\n\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/zoe.gatheomix.com\/fr\/loja\/autocolantes\/baby-on-board\/\">BABY ON BOARD<\/a><\/h3>\n\t\t\t\n\t\n\n\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\n\t\t<a href=\"https:\/\/zoe.gatheomix.com\/fr\/loja\/autocolantes\/baby-on-board\/\"  data-quantity=\"1\" class=\"button product_type_variable add-to-cart-loop\" data-product_id=\"990\" data-product_sku=\"BABY-ONBOARD-1\" aria-label=\"S\u00e9lectionner les options pour \u201cBABY ON BOARD\u201d\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span class=\"wd-action-icon\"><span class=\"wd-check-icon\"><\/span><\/span><span class=\"wd-action-text\" data-no-translation=\"\" data-trp-gettext=\"\">Lire la suite<\/span><\/a>\t<\/div>\n\n\t\n\t\n\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<div class=\"wd-product wd-col wd-hover-standard product-grid-item product type-product post-453 status-publish instock product_cat-vestuario has-post-thumbnail shipping-taxable purchasable product-type-variable\" data-loop=\"5\" data-id=\"453\">\n\t\n<div class=\"wd-product-wrapper product-wrapper\">\n\t<div class=\"wd-product-thumb product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/zoe.gatheomix.com\/fr\/loja\/vestuario\/baseball-cap\/\" class=\"wd-product-img-link product-image-link\" tabindex=\"-1\" aria-label=\"Baseball Cap\">\n\t\t\t\t\t<div class=\"wd-product-grid-slider wd-fill\">\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slide\" data-image-url=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-bsb-cap-0-430x491.jpg\" data-image-srcset=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-bsb-cap-0-430x491.jpg 430w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-bsb-cap-0-180x206.jpg 180w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-bsb-cap-0.jpg 700w\" data-image-id=\"0\"><\/div>\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slide\" data-image-url=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-bsb-cap-4-430x491.jpg\" data-image-srcset=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-bsb-cap-4-430x491.jpg 430w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-bsb-cap-4-180x206.jpg 180w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-bsb-cap-4.jpg 700w\" data-image-id=\"1\"><\/div>\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slide\" data-image-url=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-tot-bg-0-430x491.jpg\" data-image-srcset=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-tot-bg-0-430x491.jpg 430w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-tot-bg-0-180x206.jpg 180w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-tot-bg-0.jpg 700w\" data-image-id=\"2\"><\/div>\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slide\" data-image-url=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-glit-st-0-430x491.jpg\" data-image-srcset=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-glit-st-0-430x491.jpg 430w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-glit-st-0-180x206.jpg 180w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-glit-st-0.jpg 700w\" data-image-id=\"3\"><\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slider-pagin\">\n\t\t\t\t\t\t\t<div data-image-id=\"0\" class=\"wd-product-grid-slider-dot\"><\/div>\n\t\t\t\t\t\t\t<div data-image-id=\"1\" class=\"wd-product-grid-slider-dot\"><\/div>\n\t\t\t\t\t\t\t<div data-image-id=\"2\" class=\"wd-product-grid-slider-dot\"><\/div>\n\t\t\t\t\t\t\t<div data-image-id=\"3\" class=\"wd-product-grid-slider-dot\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"430\" height=\"491\" src=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-bsb-cap-0-430x491.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-bsb-cap-0-430x491.jpg 430w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-bsb-cap-0-180x206.jpg 180w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-bsb-cap-0.jpg 700w\" sizes=\"auto, (max-width: 430px) 100vw, 430px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/zoe.gatheomix.com\/fr\/compare\/\" class=\"\" data-id=\"453\" rel=\"nofollow\">\n\t\t\t\t<span class=\"wd-action-icon\">\n\t\t\t\t\t<span class=\"wd-check-icon\"><\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class=\"wd-action-text\">Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"wd-quick-view-btn wd-quick-view-icon wd-action-btn wd-style-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/zoe.gatheomix.com\/fr\/loja\/vestuario\/baseball-cap\/\"\n\t\t\t\tclass=\"open-quick-view\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"453\"\n\t\t\t\t>\n\t\t\t\t\t<span class=\"wd-action-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">\n\t\t\t\t\t\tQuick view\t\t\t\t\t<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/zoe.gatheomix.com\/fr\/wishlist\/\" data-key=\"39ec3b8ab4\" data-product-id=\"453\" rel=\"nofollow\">\n\t\t\t\t\t<span class=\"wd-action-icon\">\n\t\t\t\t\t\t<span class=\"wd-check-icon\"><\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t<\/div>\n\n\t\t<div class=\"product-element-bottom\">\n\t\n\t\n\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/zoe.gatheomix.com\/fr\/loja\/vestuario\/baseball-cap\/\">Baseball Cap<\/a><\/h3>\n\t\t\t\n\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>9,00<span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span><\/bdi><\/span><\/span>\n\n\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\n\t\t<a href=\"https:\/\/zoe.gatheomix.com\/fr\/loja\/vestuario\/baseball-cap\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_453\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"453\" data-product_sku=\"TS-1231\" aria-label=\"S\u00e9lectionner les options pour \u201cBaseball Cap\u201d\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span class=\"wd-action-icon\"><span class=\"wd-check-icon\"><\/span><\/span><span class=\"wd-action-text\" data-no-translation=\"\" data-trp-gettext=\"\">Choix des options<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_453\" class=\"screen-reader-text\">\n\t\tCe produit a plusieurs variations. Les options peuvent \u00eatre choisies sur la page du produit\t<\/span>\n\t<\/div>\n\n\t\n\t\n\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<div class=\"wd-product wd-col wd-hover-standard product-grid-item product type-product post-448 status-publish instock product_cat-vestuario has-post-thumbnail shipping-taxable purchasable product-type-variable\" data-loop=\"6\" data-id=\"448\">\n\t\n<div class=\"wd-product-wrapper product-wrapper\">\n\t<div class=\"wd-product-thumb product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/zoe.gatheomix.com\/fr\/loja\/vestuario\/bucket-hat\/\" class=\"wd-product-img-link product-image-link\" tabindex=\"-1\" aria-label=\"Bucket Hat\">\n\t\t\t\t\t<div class=\"wd-product-grid-slider wd-fill\">\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slide\" data-image-url=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-bukht-0-430x491.jpg\" data-image-srcset=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-bukht-0-430x491.jpg 430w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-bukht-0-180x206.jpg 180w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-bukht-0.jpg 700w\" data-image-id=\"0\"><\/div>\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slide\" data-image-url=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-bukht-3-430x491.jpg\" data-image-srcset=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-bukht-3-430x491.jpg 430w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-bukht-3-180x206.jpg 180w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-bukht-3.jpg 700w\" data-image-id=\"1\"><\/div>\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slide\" data-image-url=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-bsb-cap-0-430x491.jpg\" data-image-srcset=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-bsb-cap-0-430x491.jpg 430w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-bsb-cap-0-180x206.jpg 180w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-bsb-cap-0.jpg 700w\" data-image-id=\"2\"><\/div>\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slide\" data-image-url=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-ph-pr-0-430x491.jpg\" data-image-srcset=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-ph-pr-0-430x491.jpg 430w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-ph-pr-0-180x206.jpg 180w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-ph-pr-0.jpg 700w\" data-image-id=\"3\"><\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slider-pagin\">\n\t\t\t\t\t\t\t<div data-image-id=\"0\" class=\"wd-product-grid-slider-dot\"><\/div>\n\t\t\t\t\t\t\t<div data-image-id=\"1\" class=\"wd-product-grid-slider-dot\"><\/div>\n\t\t\t\t\t\t\t<div data-image-id=\"2\" class=\"wd-product-grid-slider-dot\"><\/div>\n\t\t\t\t\t\t\t<div data-image-id=\"3\" class=\"wd-product-grid-slider-dot\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"430\" height=\"491\" src=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-bukht-0-430x491.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-bukht-0-430x491.jpg 430w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-bukht-0-180x206.jpg 180w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-bukht-0.jpg 700w\" sizes=\"auto, (max-width: 430px) 100vw, 430px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/zoe.gatheomix.com\/fr\/compare\/\" class=\"\" data-id=\"448\" rel=\"nofollow\">\n\t\t\t\t<span class=\"wd-action-icon\">\n\t\t\t\t\t<span class=\"wd-check-icon\"><\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class=\"wd-action-text\">Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"wd-quick-view-btn wd-quick-view-icon wd-action-btn wd-style-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/zoe.gatheomix.com\/fr\/loja\/vestuario\/bucket-hat\/\"\n\t\t\t\tclass=\"open-quick-view\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"448\"\n\t\t\t\t>\n\t\t\t\t\t<span class=\"wd-action-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">\n\t\t\t\t\t\tQuick view\t\t\t\t\t<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/zoe.gatheomix.com\/fr\/wishlist\/\" data-key=\"39ec3b8ab4\" data-product-id=\"448\" rel=\"nofollow\">\n\t\t\t\t\t<span class=\"wd-action-icon\">\n\t\t\t\t\t\t<span class=\"wd-check-icon\"><\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t<\/div>\n\n\t\t<div class=\"product-element-bottom\">\n\t\n\t\n\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/zoe.gatheomix.com\/fr\/loja\/vestuario\/bucket-hat\/\">Bucket Hat<\/a><\/h3>\n\t\t\t\n\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>10,00<span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span><\/bdi><\/span><\/span>\n\n\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\n\t\t<a href=\"https:\/\/zoe.gatheomix.com\/fr\/loja\/vestuario\/bucket-hat\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_448\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"448\" data-product_sku=\"TS-1230\" aria-label=\"S\u00e9lectionner les options pour \u201cBucket Hat\u201d\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span class=\"wd-action-icon\"><span class=\"wd-check-icon\"><\/span><\/span><span class=\"wd-action-text\" data-no-translation=\"\" data-trp-gettext=\"\">Choix des options<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_448\" class=\"screen-reader-text\">\n\t\tCe produit a plusieurs variations. Les options peuvent \u00eatre choisies sur la page du produit\t<\/span>\n\t<\/div>\n\n\t\n\t\n\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<div class=\"wd-product wd-col wd-hover-standard product-grid-item product type-product post-463 status-publish last instock product_cat-wall-art has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"7\" data-id=\"463\">\n\t\n<div class=\"wd-product-wrapper product-wrapper\">\n\t<div class=\"wd-product-thumb product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/zoe.gatheomix.com\/fr\/loja\/wall-art\/canvas-print\/\" class=\"wd-product-img-link product-image-link\" tabindex=\"-1\" aria-label=\"Canvas Print\">\n\t\t\t\t\t<div class=\"wd-product-grid-slider wd-fill\">\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slide\" data-image-url=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-cn-pr-0-430x491.jpg\" data-image-srcset=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-cn-pr-0-430x491.jpg 430w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-cn-pr-0-180x206.jpg 180w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-cn-pr-0.jpg 700w\" data-image-id=\"0\"><\/div>\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slide\" data-image-url=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-c-ts-11-430x491.jpg\" data-image-srcset=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-c-ts-11-430x491.jpg 430w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-c-ts-11-180x206.jpg 180w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-c-ts-11.jpg 700w\" data-image-id=\"1\"><\/div>\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slide\" data-image-url=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-sks-0-430x491.jpg\" data-image-srcset=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-sks-0-430x491.jpg 430w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-sks-0-180x206.jpg 180w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-sks-0.jpg 700w\" data-image-id=\"2\"><\/div>\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slide\" data-image-url=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-sq-cor-st-0-430x491.jpg\" data-image-srcset=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-sq-cor-st-0-430x491.jpg 430w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-sq-cor-st-0-180x206.jpg 180w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-sq-cor-st-0.jpg 700w\" data-image-id=\"3\"><\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slider-pagin\">\n\t\t\t\t\t\t\t<div data-image-id=\"0\" class=\"wd-product-grid-slider-dot\"><\/div>\n\t\t\t\t\t\t\t<div data-image-id=\"1\" class=\"wd-product-grid-slider-dot\"><\/div>\n\t\t\t\t\t\t\t<div data-image-id=\"2\" class=\"wd-product-grid-slider-dot\"><\/div>\n\t\t\t\t\t\t\t<div data-image-id=\"3\" class=\"wd-product-grid-slider-dot\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"430\" height=\"491\" src=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-cn-pr-0-430x491.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-cn-pr-0-430x491.jpg 430w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-cn-pr-0-180x206.jpg 180w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-cn-pr-0.jpg 700w\" sizes=\"auto, (max-width: 430px) 100vw, 430px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/zoe.gatheomix.com\/fr\/compare\/\" class=\"\" data-id=\"463\" rel=\"nofollow\">\n\t\t\t\t<span class=\"wd-action-icon\">\n\t\t\t\t\t<span class=\"wd-check-icon\"><\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class=\"wd-action-text\">Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"wd-quick-view-btn wd-quick-view-icon wd-action-btn wd-style-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/zoe.gatheomix.com\/fr\/loja\/wall-art\/canvas-print\/\"\n\t\t\t\tclass=\"open-quick-view\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"463\"\n\t\t\t\t>\n\t\t\t\t\t<span class=\"wd-action-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">\n\t\t\t\t\t\tQuick view\t\t\t\t\t<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/zoe.gatheomix.com\/fr\/wishlist\/\" data-key=\"39ec3b8ab4\" data-product-id=\"463\" rel=\"nofollow\">\n\t\t\t\t\t<span class=\"wd-action-icon\">\n\t\t\t\t\t\t<span class=\"wd-check-icon\"><\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t<\/div>\n\n\t\t<div class=\"product-element-bottom\">\n\t\n\t\n\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/zoe.gatheomix.com\/fr\/loja\/wall-art\/canvas-print\/\">Canvas Print<\/a><\/h3>\n\t\t\t\n\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>9,00<span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span><\/bdi><\/span><\/span>\n\n\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\n\t\t<a href=\"\/fr\/wp-json\/wp\/v2\/pages\/838?add-to-cart=463\"  data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"463\" data-product_sku=\"TS-1235\" aria-label=\"Ajouter au panier\u00a0: \u201cCanvas Print\u201d\" rel=\"nofollow\" data-success_message=\"\u00ab\u00a0Canvas Print\u00a0\u00bb a \u00e9t\u00e9 ajout\u00e9 \u00e0 votre panier\" role=\"button\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\"><span class=\"wd-action-icon\"><span class=\"wd-check-icon\"><\/span><\/span><span class=\"wd-action-text\" data-no-translation=\"\" data-trp-gettext=\"\">Ajouter au panier<\/span><\/a>\t<\/div>\n\n\t\n\t\n\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<div class=\"wd-product wd-col wd-hover-standard product-grid-item product type-product post-520 status-publish first instock product_cat-autocolantes has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"8\" data-id=\"520\">\n\t\n<div class=\"wd-product-wrapper product-wrapper\">\n\t<div class=\"wd-product-thumb product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/zoe.gatheomix.com\/fr\/loja\/autocolantes\/circle-stickers\/\" class=\"wd-product-img-link product-image-link\" tabindex=\"-1\" aria-label=\"Circle Stickers\">\n\t\t\t\t\t<div class=\"wd-product-grid-slider wd-fill\">\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slide\" data-image-url=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-crc-cor-st-0-430x491.jpg\" data-image-srcset=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-crc-cor-st-0-430x491.jpg 430w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-crc-cor-st-0-180x206.jpg 180w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-crc-cor-st-0.jpg 700w\" data-image-id=\"0\"><\/div>\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slide\" data-image-url=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-tot-bg-0-430x491.jpg\" data-image-srcset=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-tot-bg-0-430x491.jpg 430w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-tot-bg-0-180x206.jpg 180w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-tot-bg-0.jpg 700w\" data-image-id=\"1\"><\/div>\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slide\" data-image-url=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-bukht-3-430x491.jpg\" data-image-srcset=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-bukht-3-430x491.jpg 430w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-bukht-3-180x206.jpg 180w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-bukht-3.jpg 700w\" data-image-id=\"2\"><\/div>\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slide\" data-image-url=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-c-ts-8-430x491.jpg\" data-image-srcset=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-c-ts-8-430x491.jpg 430w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-c-ts-8-180x206.jpg 180w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-c-ts-8.jpg 700w\" data-image-id=\"3\"><\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\t\t\t\t\t<div class=\"wd-product-grid-slider-pagin\">\n\t\t\t\t\t\t\t<div data-image-id=\"0\" class=\"wd-product-grid-slider-dot\"><\/div>\n\t\t\t\t\t\t\t<div data-image-id=\"1\" class=\"wd-product-grid-slider-dot\"><\/div>\n\t\t\t\t\t\t\t<div data-image-id=\"2\" class=\"wd-product-grid-slider-dot\"><\/div>\n\t\t\t\t\t\t\t<div data-image-id=\"3\" class=\"wd-product-grid-slider-dot\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"430\" height=\"491\" src=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-crc-cor-st-0-430x491.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"\" srcset=\"https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-crc-cor-st-0-430x491.jpg 430w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-crc-cor-st-0-180x206.jpg 180w, https:\/\/zoe.gatheomix.com\/wp-content\/uploads\/2025\/03\/ps-crc-cor-st-0.jpg 700w\" sizes=\"auto, (max-width: 430px) 100vw, 430px\" \/>\t\t<\/a>\n\n\t\t\n\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/zoe.gatheomix.com\/fr\/compare\/\" class=\"\" data-id=\"520\" rel=\"nofollow\">\n\t\t\t\t<span class=\"wd-action-icon\">\n\t\t\t\t\t<span class=\"wd-check-icon\"><\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class=\"wd-action-text\">Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"wd-quick-view-btn wd-quick-view-icon wd-action-btn wd-style-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/zoe.gatheomix.com\/fr\/loja\/autocolantes\/circle-stickers\/\"\n\t\t\t\tclass=\"open-quick-view\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"520\"\n\t\t\t\t>\n\t\t\t\t\t<span class=\"wd-action-icon\"><\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">\n\t\t\t\t\t\tQuick view\t\t\t\t\t<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/zoe.gatheomix.com\/fr\/wishlist\/\" data-key=\"39ec3b8ab4\" data-product-id=\"520\" rel=\"nofollow\">\n\t\t\t\t\t<span class=\"wd-action-icon\">\n\t\t\t\t\t\t<span class=\"wd-check-icon\"><\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<span class=\"wd-action-text\">Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t<\/div>\n\n\t\t<div class=\"product-element-bottom\">\n\t\n\t\n\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/zoe.gatheomix.com\/fr\/loja\/autocolantes\/circle-stickers\/\">Circle Stickers<\/a><\/h3>\n\t\t\t\n\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi>4,00<span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span><\/bdi><\/span><\/span>\n\n\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\n\t\t<a href=\"\/fr\/wp-json\/wp\/v2\/pages\/838?add-to-cart=520\"  data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"520\" data-product_sku=\"TS-1248\" aria-label=\"Ajouter au panier\u00a0: \u201cCircle Stickers\u201d\" rel=\"nofollow\" data-success_message=\"\u00ab\u00a0Circle Stickers\u00a0\u00bb a \u00e9t\u00e9 ajout\u00e9 \u00e0 votre panier\" role=\"button\" data-no-translation-aria-label=\"\" data-no-translation-data-success_message=\"\"><span class=\"wd-action-icon\"><span class=\"wd-check-icon\"><\/span><\/span><span class=\"wd-action-text\" data-no-translation=\"\" data-trp-gettext=\"\">Ajouter au panier<\/span><\/a>\t<\/div>\n\n\t\n\t\n\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t\t<\/div>\n\t\t\t<\/div><\/div><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"Vitra. T-shirt The classic t-shirt is a versatile wardrobe staple. It\u2019s made of soft, comfortable cotton and has a relaxed","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-838","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/zoe.gatheomix.com\/fr\/wp-json\/wp\/v2\/pages\/838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zoe.gatheomix.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/zoe.gatheomix.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/zoe.gatheomix.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zoe.gatheomix.com\/fr\/wp-json\/wp\/v2\/comments?post=838"}],"version-history":[{"count":15,"href":"https:\/\/zoe.gatheomix.com\/fr\/wp-json\/wp\/v2\/pages\/838\/revisions"}],"predecessor-version":[{"id":1021,"href":"https:\/\/zoe.gatheomix.com\/fr\/wp-json\/wp\/v2\/pages\/838\/revisions\/1021"}],"wp:attachment":[{"href":"https:\/\/zoe.gatheomix.com\/fr\/wp-json\/wp\/v2\/media?parent=838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}